{"id":1119,"date":"2013-09-23T13:23:14","date_gmt":"2013-09-23T12:23:14","guid":{"rendered":"http:\/\/www.zweitfrau.eu\/wordpress\/?p=1119"},"modified":"2013-09-29T06:13:34","modified_gmt":"2013-09-29T05:13:34","slug":"congratulation","status":"publish","type":"post","link":"http:\/\/www.zweitfrau.eu\/wordpress\/congratulation\/","title":{"rendered":"Congratulation"},"content":{"rendered":"<p><center><a href=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/zweitfrau_190920131.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/zweitfrau_190920131-800x360.jpg\" alt=\"\" title=\"zweitfrau_19092013\" width=\"400\" height=\"180\" class=\"alignnone size-medium wp-image-1121\" srcset=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/zweitfrau_190920131-800x360.jpg 800w, http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/zweitfrau_190920131.jpg 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/center><br \/>\n&nbsp;<br \/>\nLiebe Band Zweitfrau,<br \/>\nheute ist es mal an der Zeit, Euch vor den Vorhang zu holen und Euch f\u00fcr die Arbeit zu danken, die Ihr in letzter Zeit vollbracht habt.<br \/>\nVor ca. einem Jahr habt Ihr angek\u00fcndigt, dass Ihr zum 10. Jahrestag Eurer Gr\u00fcndung ein Album herausbringen werdet und dazu, neben Videos zu &#8222;Ein Funkeln&#8220;, &#8222;Dude I Rock&#8220; und &#8222;Perfekt&#8220; auch eine Dokumentation (siehe unten) \u00fcber diese Zeit. Das h\u00f6rt sich auf den ersten Blick recht einfach an, der Teufel steckt aber im Detail, das hei\u00dft in der Ausf\u00fchrung.<br \/>\nJetzt ist Alles vollbracht, das Album, die Videos zu den Singles, die Dokumentation uuuuund die Albumpr\u00e4sentation im feierlichen Rahmen. Die Medienarbeit haben wir noch gar nicht erw\u00e4hnt, denn darin seid Ihr wahre Meister.<br \/>\n<!--more--><br \/>\nFernsehen und Rundfunk mit Reportagen, Zeitungen mit feinen Artikeln sind Euer Lohn.<br \/>\nAm Erfreulichsten aber f\u00fcr uns die Fangemeinde ist, dass die allumfassende Rundfunkanstalt OE3 den Titel &#8222;Perfekt&#8220; t\u00e4glich in Rotation sendet. Der Erfolg ist Euer ganz besonderer Lohn.<br \/>\nDer Fanclub, der Euch ebenfalls 10 Jahre begleitet und dokumentiert hat, ist stolz auf Euch und singt f\u00fcr Euch <strong><i>Congratulation<\/i><\/strong>. Besonders danken wir Dir, liebe Diana, f\u00fcr Deinen unerm\u00fcdlichen Tatendrang, eine Band immer wieder zu animieren und vor allem medial in den Mittelpunkt zu stellen. Aber auch Lex und Martin haben uns durch die musikalische und medienwirksame Gestaltung wie Arrangement, Bild- und Tonaufnahmen gefesselt. Und nicht zu vergessen Piotr und Christopher, die die Troika perfekt erg\u00e4nzen durch Songwriting und hei\u00dfe Rhythmen.<\/p>\n<p>Die Redaktion gratuliert Euch nochmals recht herzlich und Euer Song hei\u00dft nicht umsonst perfekt.<br \/>\n&nbsp;<br \/>\nHier die Zweitfrau Doku 10<br \/>\n&nbsp;<br \/> <br \/>\n<center><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/UIqp_WzZhFg\" frameborder=\"0\" height=\"208\" width=\"368\"><\/iframe><\/center>Video <span style=\"font-size:10pt;\">&copy; 2013<\/span> by Zweitfrau<br \/>\n&nbsp;<br \/>\nWie schon angek\u00fcndigt, der Fanclub hat von der Albumpr\u00e4sentation nicht nur Bilder gemacht, sondern auch videographiert. Ergebnis &#8230;<br \/>\n&nbsp;<br \/>\n<center>\t<video id=\"wp_mep_1\" src=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/2013\/09\/10_albumpraesentation_chaya_fuera_19092013.mp4\"  width=\"368\" height=\"215\" poster=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/2013\/09\/10_albumpraesentation_chaya_fuera_19092013.jpg\" controls=\"controls\" preload=\"none\"  >\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t<\/video>\r\n<script type=\"text\/javascript\">\r\njQuery(document).ready(function($) {\r\n\t$('#wp_mep_1').mediaelementplayer({\r\n\t\tm:1\r\n\t\t\r\n\t\t,features: ['playpause','current','progress','duration','volume','tracks','fullscreen']\r\n\t\t\r\n\t});\r\n});\r\n<\/script>\r\n<\/center>Video <span style=\"font-size:10pt;\">&copy; 2013<\/span> by Fanclub<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Liebe Band Zweitfrau, heute ist es mal an der Zeit, Euch vor den Vorhang zu holen und Euch f\u00fcr die Arbeit zu danken, die Ihr in letzter Zeit vollbracht habt. Vor ca. einem Jahr habt Ihr angek\u00fcndigt, dass Ihr zum 10. Jahrestag Eurer Gr\u00fcndung ein Album herausbringen werdet und dazu, neben Videos zu &#8222;Ein [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1119","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/1119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/comments?post=1119"}],"version-history":[{"count":0,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/1119\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/media?parent=1119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/categories?post=1119"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/tags?post=1119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}