{"id":127,"date":"2008-07-16T21:55:07","date_gmt":"2008-07-16T19:55:07","guid":{"rendered":"http:\/\/www.zweitfrau.eu\/wordpress\/?p=127"},"modified":"2008-08-30T17:51:15","modified_gmt":"2008-08-30T15:51:15","slug":"13-regenbogenparade-abschluskonzert","status":"publish","type":"post","link":"http:\/\/www.zweitfrau.eu\/wordpress\/13-regenbogenparade-abschluskonzert\/","title":{"rendered":"13. Regenbogenparade | Abschlu\u00dfkonzert"},"content":{"rendered":"<p><strong>Video mit &#8222;Vielleichter&#8220; beim Abschlu\u00dfkonzert der 13. Regenbogenparade<\/strong><br \/>\n&nbsp;&nbsp;<\/p>\n<p>[MEDIA=19]<\/p>\n<p>Fotos vom Konzert kannst Du Dir auf der offiziellen Zweitfrau-Seite <a href=\"http:\/\/www.zweitfrau.com\/foto\/live\/\">[hier]<\/a> ansehen (Du verl\u00e4sst dabei die Fanseite! Komme aber wieder zur\u00fcck!).<\/p>\n<p><strong>Wien, Heldenplatz 12.07.2008<\/strong><br \/>\nDie 13. Regenbogenparade ist angesetzt. Es geht farbenfroh, lasziv, cool, ja ultracool zu. Burschen und M\u00e4dchen, rund 120.000 (laut Angabe der Veranstalter), demonstrieren f\u00fcr Gleichberechtigung Homosexueller. Alles ist schr\u00e4g und schrill! Vom Stadtpark geht es &#8222;andersrum&#8220; entlang der Ringstra\u00dfe, vorbei am Parlament zum Heldenplatz zur B\u00fchne f\u00fcr das Abschlusskonzert. Tausende Schaulustige verfolgen das bunte, schr\u00e4ge Treiben entlang des Ringes. Manche sch\u00fctteln den Kopf. <i>Gibt&#8217;s denn sowas?<\/i><br \/>\nEine perfekte Choreografie, auch Petrus spielt mit. Strahlend blauer Himmel, sommerliche Temperaturen, darf das alles wahr sein?<br \/>\n<a href='http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/diana_kurier.jpg'><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/diana_kurier-300x225.jpg\" alt=\"\" title=\"diana_kurier\" width=\"300\" height=\"225\" style=\"float:left; margin-right:20px;  margin-bottom:10px;\" class=\"alignnone size-medium wp-image-126\" srcset=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/diana_kurier-300x225.jpg 300w, http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/diana_kurier.jpg 442w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Wir warten auf den Auftritt von Zweitfrau und erinnern uns. Vor einigen Wochen am selben Ort setzte str\u00f6mender Regen ein, die Zuh\u00f6rer mussten fl\u00fcchten und das Konzert wurde unter Lebensgefahr beendet. Sollte es auch heute so enden, denn mit dem B\u00fchnenauftritt Dianas beginnt sich das Wetter zu ver\u00e4ndern, schwere Gewitter mit Hagel sind angesagt.<!--more--><br \/>\nUnd dann Zweitfrau. Sie legen eine 45min\u00fctige Show hin , dass den tausenden Besuchern die Spuke weg bleibt. Die Masse geht ungeheuerlich mit und als Diana dann den Text von DICKE WEIBER UND ROULETTE erg\u00e4nzt und neben <i>Ich geh als M\u00e4dchen mit M\u00e4dchen ins Bett<\/i> den Refrain <i>Ich geh als Junge mit Jungs ins Bett<\/i> intoniert, ist ein vorl\u00e4ufiger Siedepunkt des Abends erreicht, der unbedingt gek\u00fchlt werden muss. Nicht nur mit Bier und k\u00fchlen Getr\u00e4nken. Mit dem letzten Takt setzt nicht nur st\u00fcrmischer Applaus ein, sondern orkanartige Windst\u00f6sse fegen durch die dicht gedr\u00e4ngten Reihen und lassen B\u00f6ses ahnen.<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/regenbogenparde_gewitter.jpg\" alt=\"\" title=\"regenbogenparde_gewitter\" width=\"300\" height=\"225\" style=\"float:left; margin-right:20px;  margin-bottom:10px;\" class=\"alignnone size-medium wp-image-125\" \/> Wenige Minuten sp\u00e4ter setzte ein m\u00f6rderisches Gewitter ein, das dem herrlichen Treiben aber kein Ende setzte!!<br \/>\nDanke Petrus, dass Du die Zugabe noch abwartetest; wir schlie\u00dfen daraus, dass auch Dir der Zweitfrau-Gig gefallen hat.<br \/>\nDas Programm wurde fortgesetzt.<br \/>\n(FC)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Video mit &#8222;Vielleichter&#8220; beim Abschlu\u00dfkonzert der 13. Regenbogenparade &nbsp;&nbsp; [MEDIA=19] Fotos vom Konzert kannst Du Dir auf der offiziellen Zweitfrau-Seite [hier] ansehen (Du verl\u00e4sst dabei die Fanseite! Komme aber wieder zur\u00fcck!). Wien, Heldenplatz 12.07.2008 Die 13. Regenbogenparade ist angesetzt. Es geht farbenfroh, lasziv, cool, ja ultracool zu. Burschen und M\u00e4dchen, rund 120.000 (laut Angabe der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[149],"class_list":["post-127","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-allgemein"],"_links":{"self":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/comments?post=127"}],"version-history":[{"count":0,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/127\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/media?parent=127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/categories?post=127"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/tags?post=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}