{"id":248,"date":"2008-11-05T11:59:30","date_gmt":"2008-11-05T09:59:30","guid":{"rendered":"http:\/\/www.zweitfrau.eu\/wordpress\/?p=248"},"modified":"2008-11-10T12:48:02","modified_gmt":"2008-11-10T10:48:02","slug":"obama-rede-eine-botschaft-fur-die-welt","status":"publish","type":"post","link":"http:\/\/www.zweitfrau.eu\/wordpress\/obama-rede-eine-botschaft-fur-die-welt\/","title":{"rendered":"Obama Rede &#8211; Eine Botschaft f\u00fcr die Welt"},"content":{"rendered":"<p><span style=\"line-height: 12pt;\">Der Fanclub besch\u00e4ftigt sich zwar im Allgemeinen nicht mit Politik!<br \/>\nDie au\u00dfergew\u00f6hnliche Situation der Wahl eines AfroAmerikaners zum USA Pr\u00e4sidenten nach G.W. Bush geht aber auch an uns nicht vor\u00fcber und so wollen wir den Interessierten unter Euch die Obama-Rede, die er nach seinem Wahlsieg vor mehr als 100.000 Menschen in Chicago hielt und in der er Leitlinien seiner Pr\u00e4sidentschaft aufzeigt, nicht vorenthalten. Es betrifft uns alle!<br \/>\n<\/span><span style=\"line-height: 12pt;\">Das 17-min\u00fctige Video kannst Du <a href=\"http:\/\/www.zweitfrau.eu\/wordpress\/?p=250&#038;preview=true\">hier<\/a> sehen.<br \/>\nObamas Rede hat nach einer inoffiziellen \u00dcbersetzung der Nachrichtenagentur AP folgenden, leicht gek\u00fcrzten Wortlaut:<\/span><\/p>\n<blockquote><p><a href='http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/obama_2008_msrs109_new.jpg'><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/obama_2008_msrs109_new-300x225.jpg\" alt=\"\" title=\"Obama 2008\" width=\"300\" height=\"225\" style=\"float:left; margin-right:20px;  margin-bottom:10px;\" class=\"alignnone size-medium wp-image-249\" srcset=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/obama_2008_msrs109_new-300x225.jpg 300w, http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/obama_2008_msrs109_new.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"line-height: 12pt;\">Hallo, Chicago. Wenn es da drau\u00dfen irgendjemand gibt, der noch zweifelt, dass Amerika ein Ort ist, wo alles m\u00f6glich ist, der sich noch fragt, ob der Traum unserer Gr\u00fcnder heute lebendig ist, der Fragen zur Kraft unserer Demokratie aufwirft, hat heute eine Antwort bekommen. Es ist die Antwort, die von den Warteschlangen vor Schulen und Kirchen gegeben wird, in Zahlen, die diese Nation nie gesehen hat, von Leuten, die drei Stunden und vier Stunden gewartet haben, viele zum ersten Mal in ihrem Leben, weil sie glaubten, dass es dieses Mal anders sein muss, dass ihre Stimmen diesen Unterschied ausmachen k\u00f6nnen.<br \/>\nEs ist die Antwort, die von Jungen und Alten gegeben wird, von Reichen und Armen, Demokraten und Republikanern, Schwarzen, Wei\u00dfen, Hispanics, Asiaten, Indianern, Schwulen und Heterosexuellen, Behinderten und Nichtbehinderten. Von Amerikanern, die der Welt eine Botschaft geschickt haben, dass wir keineswegs nur eine Ansammlung von Einzelmenschen oder eine Kollektion von roten und blauen Staaten sind. Wir sind die Vereinigten Staaten von Amerika und werden das immer sein.<\/span><br \/>\n&#8230;<!--more--><br \/>\n<span style=\"line-height: 12pt;\">Es hat eine lange Zeit gedauert, aber heute abend ist der Wandel in Amerika angekommen &#8211; weil wir es geschafft haben am Datum dieser Wahl in diesem entscheidenden Augenblick. Etwas fr\u00fcher an diesem Abend habe ich einen au\u00dfergew\u00f6hnlich freundlichen Anruf von Senator McCain erhalten. Senator McCain hat lange und hart in diesem Wahlkampf gek\u00e4mpft. Und er hat noch l\u00e4nger und h\u00e4rter f\u00fcr das Land gek\u00e4mpft, das er liebt. Er hat Opfer f\u00fcr Amerika ertragen, die sich die meisten von uns noch nicht einmal im Ansatz vorstellen k\u00f6nnen. Uns geht es besser dank des Dienstes, den dieser tapfere und selbstlose F\u00fchrer geleistet hat. Ich gratuliere ihm, ich gratuliere Gouverneurin Palin f\u00fcr alles, was sie erreicht haben. Und ich freue mich darauf, mit ihnen zusammenzuarbeiten, um in den kommenden Monaten das Versprechen dieser Nation zu erneuern.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Ich will meinem Partner auf dieser Reise danken, einem Mann, der mit ganzem Herzen im Wahlkampf dabei war &#8230;, dem gew\u00e4hlten Vizepr\u00e4sidenten der Vereinigten Staaten, Joe Biden. Und ich w\u00fcrde heute abend nicht hier stehen ohne die unabl\u00e4ssige Unterst\u00fctzung meiner besten Freundin in den vergangenen 16 Jahren, dem Fels unserer Familie, der Liebe meines Lebens, der n\u00e4chsten First Lady der Nation, Michelle Obama.<\/span><br \/>\n&#8230;<br \/>\n<span style=\"line-height: 12pt;\">Aber \u00fcber allem werde ich nie vergessen, wem dieser Sieg in Wahrheit geh\u00f6rt. Er geh\u00f6rt euch. &#8230; Ich war nie der wahrscheinlichste Kandidat f\u00fcr dieses Amt. Wir haben nicht mit viel Geld oder viel Unterst\u00fctzung angefangen. Unser Wahlkampf entstand nicht in den S\u00e4len in Washington. Er begann in den Hinterh\u00f6fen von Des Moines und in den Wohnzimmern in Concord und den Vorg\u00e4rten von Charleston. Er wurde gestaltet von arbeitenden M\u00e4nnern und Frauen, die in ihre kleinen Ersparnisse gegriffen haben, um 5 oder 10 oder 20 $ f\u00fcr die Sache zu geben.<\/span><br \/>\n&#8230;<br \/>\n<span style=\"line-height: 12pt;\">Dies ist euer Sieg. Ich wei\u00df, dass ihr das nicht einfach getan habt, um eine Wahl zu gewinnen. Und ich wei\u00df, dass ihr das nicht f\u00fcr mich getan habt. Ihr habt es getan, weil ihr das gewaltige Ausma\u00df der vor uns liegenden Aufgabe versteht. Denn selbst wenn wir heute abend feiern, wissen wir, dass die Herausforderungen von morgen die gr\u00f6\u00dften unseres Lebens sind &#8211; zwei Kriege, ein Planet in h\u00f6chster Gefahr, die schwerste Finanzkrise in einem Jahrhundert. <\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Selbst wenn wir heute abend hier stehen, wissen wir, dass tapfere Amerikaner in den W\u00fcsten des Iraks und in den Bergen Afghanistans aufwachen, um ihr Leben f\u00fcr uns zu riskieren. Da sind M\u00fctter und V\u00e4ter, die wach liegen, wenn die Kinder schon eingeschlafen sind, und sich fragen, wie sie die Hypothek finanzieren oder ihre Arztrechnung bezahlen oder genug sparen f\u00fcr den Hochschulunterricht ihres Kindes.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Es m\u00fcssen neue Energien genutzt, neue Arbeitspl\u00e4tze geschaffen und neue Schulen gebaut werden, auf Bedrohungen muss reagiert werden, und B\u00fcndnisse m\u00fcssen erneuert werden. Die Stra\u00dfe vor uns wird lang sein. Unser Anstieg wird steil sein. Wir werden nicht in einem Jahr oder selbst in einer Amtszeit dort ankommen. Aber, Amerika, ich war nie hoffnungsvoller als heute abend, dass wir dort hinkommen werden.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Ich verspreche euch, wir als ein Volk werden dort hingelangen.<br \/>\n(Rufe: Yes we can! Yes we can! Yes we can!)<br \/>\n<\/span><br \/>\n<span style=\"line-height: 12pt;\">Es wird R\u00fcckschl\u00e4ge und falsche Ans\u00e4tze geben. Es gibt viele, die nicht mit jeder Entscheidung oder jeder Politik einverstanden sein werden, die ich als Pr\u00e4sident mache. Und wir wissen, dass die Regierung nicht jedes Problem l\u00f6sen kann. Aber ich werde immer ehrlich mit euch umgehen, wenn es um die Herausforderungen geht, die vor uns liegen.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Ich werde euch zuh\u00f6ren, vor allem, wenn wir verschiedener Meinung sind. Und vor allem werde ich euch bitten, euch der Arbeit anzuschlie\u00dfen, um diese Nation zu erneuern, auf die einzige Art, wie dies in Amerika seit 221 Jahren getan worden ist &#8211; Block um Block, Stein um Stein, schwielige Hand um schwielige Hand.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Was vor 21 Monaten in den Tiefen des Winters begann, kann nicht in dieser Herbstnacht enden. Dieser Sieg allein ist noch nicht der Wandel, den wir anstreben. Er ist nur die Chance f\u00fcr uns, diesen Wandel herbeizuf\u00fchren. Und das kann nicht geschehen, wenn wir zur\u00fcckkehren zu der Art, wie die Dinge waren. Es kann nicht ohne euch geschehen, ohne einen neuen Geist des Dienstes, einen neuen Opfergeist. Daher lasst uns einen neuen Geist des Patriotismus entwickeln, der Verantwortung, bei der jeder von uns beschlie\u00dft, einzuspringen und h\u00e4rter zu arbeiten und nicht nur nach uns selbst, sondern auch nach den anderen zu schauen.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Lasst uns daran denken, dass uns diese Finanzkrise wenn \u00fcberhaupt gelehrt hat, dass wir keine bl\u00fchende Wall Street haben k\u00f6nnen, w\u00e4hrend die Main Street leidet. In diesem Land sind wir eine Nation, ein Volk, wennh wir uns erheben oder fallen.<\/span><br \/>\n&#8230;<br \/>\n<span style=\"line-height: 12pt;\">Und an diejenigen Amerikaner, deren Unterst\u00fctzung ich erst noch erlangen muss: Ich mag heute nicht eure Stimme bekommen haben, aber ich h\u00f6re eure Stimmen. Ich brauche eure Hilfe. Und ich werde auch euer Pr\u00e4sident sein.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Und an alle, die heute abend jenseits unserer K\u00fcsten zuschauen, von Parlamenten und Pal\u00e4sten, an die, die in den vergessenen Ecken der Welt vor dem Radio zusammensitzen &#8211; unsere Geschichten sind verschieden, aber wir teilen ein Schicksal, und eine neue Morgend\u00e4mmerung der amerikanischen F\u00fchrungskraft ist da.<br \/>\n<\/span><br \/>\n<span style=\"line-height: 12pt;\">An diejenigen, die diese Welt niederrei\u00dfen wollen: Wir werden euch besiegen. An diejenigen, die Frieden und Sicherheit wollen: Wir unterst\u00fctzen euch. Und an diejenigen, die sich gefragt haben, ob das Leuchtfeuer Amerikas noch so hell brennt: Heute abend haben wir einmal mehr bewiesen, dass die wahre St\u00e4rke unserer Nation nicht von der Macht unserer Waffen oder dem Ausma\u00df unsereres Wohlstands kommt, sondern von der andauernden Kraft unserer Ideale: Demokratie, Freiheit, Chancen und unabl\u00e4ssige Hoffnung.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Dass ist der wahre Geist Amerikas: Dass Amerika sich \u00e4ndern kann. Unsere Union kann vervollkommnet werden. Was wir schon erreicht haben, gibt uns Hoffnung f\u00fcr das, was wir morgen erreichen k\u00f6nnen und m\u00fcssen.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Diese Wahl hatte viele erstmalige Dinge und viele Geschichten, die noch \u00fcber Generationen hinweg erz\u00e4hlt werden. Aber eine ist heute abend in meinem Kopf von einer Frau, die ihre Stimme in Atlanta abgegeben hat. Sie ist wie die Millionen anderen, die in der Schlange gewartet haben, damit bei dieser Wahl ihre Stimme geh\u00f6rt wird &#8211; mit einer Ausnahme: Ann Nixon Cooper ist 106 Jahre alt.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Sie wurde gerade eine Generation nach der Sklaverei geboren, in einer Zeit, als es keine Autos auf der Stra\u00dfe und keine Flugzeuge im Himmel gab, als jemand wie sie aus zwei Gr\u00fcnden nicht w\u00e4hlen konnte: Weil sie eine Frau ist und wegen ihrer Hautfarbe.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Und heute abend denke ich an alles, was sie das ganze Jahrhundert hinweg in Amerika gesehen hat &#8211; den Kummer und die Hoffnung, den Kampf und den Fortschritt, die Zeit, in der wir gesagt bekamen, dass wir nicht k\u00f6nnen, und die Leute, die am amerikanischen Glauben festhielten: Ja, wir k\u00f6nnen.<br \/>\n<\/span><br \/>\n<span style=\"line-height: 12pt;\">Wenn da Verzweiflung im Staub und Depression im Land war, erlebte sie eine Nation, die ihre Angst mit einem New Deal bezwang, mit neuen Arbeitspl\u00e4tzen, einem neuen Sinn f\u00fcr gemeinsame Ziele. Ja, wir k\u00f6nnen.<br \/>\n(Rufe: Yes we can)<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Als die Bomben auf unseren Hafen fielen und Tyrannei die Welt bedrohte, erlebte sie, wie eine Generation sich zur Gr\u00f6\u00dfe erhob und eine Demokratie gerettet wurde. Ja, wir k\u00f6nnen.<br \/>\n(Rufe: Yes we can)<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Sie war da f\u00fcr die Busse in Montgomery, die Wasserschl\u00e4uche in Birmingham, eine Br\u00fccke in Selma, und da gab es einen Prediger aus Atlanta, der einem Volk gesagt hat: We Shall Overcome. Ja, wir k\u00f6nnen.<br \/>\n(Rufe: Yes we can)<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Ein Mann ist auf dem Mond gelandet, eine Mauer wurde in Berlin niedergerissen, eine Welt wurde verbunden durch unsere eigene Wissenschaft und Vorstellungskraft. Und in diesem Jahr, bei dieser Wahl, ber\u00fchrte sie mit ihrem Finger einen Bildschirm und gab ihre Stimme ab, weil sie nach 106 Jahren in Amerika, durch die besten Zeiten und dunkelsten Stunden hinweg, wusste, wie Amerika sich wandeln kann. Ja, wir k\u00f6nnen.<br \/>\n(Rufe: Yes we can)<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Amerika, wir sind so weit gekommen. Wir haben so viel gesehen. Aber es ist noch so viel mehr zu tun. So lasst uns heute abend fragen, ob unsere Kinder leben sollen, um das n\u00e4chste Jahrhundert zu sehen, ob meine T\u00f6chter so gl\u00fccklich sein werden, so lange zu leben wie Ann Nixon Cooper, welchen Wandel werden sie dann erleben? Welchen Fortschritt werden wir dann gemacht haben?<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Dies ist unsere Chance, auf diesen Ruf zu antworten. Das ist unser Augenblick. Das ist unsere Zeit, unser Volk zur\u00fcck zur Arbeit zu bringen und Chancen f\u00fcr unsere Kinder zu er\u00f6ffnen, Wohlstand wiederherzustellen und die Sache des Friedens voranzubringen, den amerikanischen Traum zur\u00fcckzugewinnen und diese fundamentale Wahrheit zu bekr\u00e4ftigen, dass wir aus vielen heraus eins sind, dass wir hoffen, w\u00e4hrend wir atmen. Und wenn wir auf Zynismus und Zweifel sto\u00dfen und auf diejenigen, die sagen, wir k\u00f6nnen das nicht, dass wir dann mit jenem zeitlosen Glauben antworten, der den Geist eines Volkes zusammenfasst: Ja, wir k\u00f6nnen.<\/span><\/p>\n<p><span style=\"line-height: 12pt;\">Danke. Gott segne euch. Und m\u00f6ge Gott die Vereinigten Staaten von Amerika segnen. <\/span><br \/>\n<i>(AP)<br \/>\nZitatende<\/i><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Der Fanclub besch\u00e4ftigt sich zwar im Allgemeinen nicht mit Politik! Die au\u00dfergew\u00f6hnliche Situation der Wahl eines AfroAmerikaners zum USA Pr\u00e4sidenten nach G.W. Bush geht aber auch an uns nicht vor\u00fcber und so wollen wir den Interessierten unter Euch die Obama-Rede, die er nach seinem Wahlsieg vor mehr als 100.000 Menschen in Chicago hielt und in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-248","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/comments?post=248"}],"version-history":[{"count":0,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/248\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/media?parent=248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/categories?post=248"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/tags?post=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}