{"id":764,"date":"2010-08-04T11:21:12","date_gmt":"2010-08-04T09:21:12","guid":{"rendered":"http:\/\/www.zweitfrau.eu\/wordpress\/?p=764"},"modified":"2010-08-06T11:30:44","modified_gmt":"2010-08-06T09:30:44","slug":"kroneat-song-contest-voting","status":"publish","type":"post","link":"http:\/\/www.zweitfrau.eu\/wordpress\/kroneat-song-contest-voting\/","title":{"rendered":"Krone.at Song Contest Voting"},"content":{"rendered":"<p>Wie der ORF auf seiner Website mitteilt, wird \u00d6sterreich beim Eurovision Song Contest 2011 wieder vertreten sein.<br \/>\n&nbsp;<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/eurovision_web.jpg\" alt=\"eurovision_web\" title=\"eurovision_web\" width=\"150\" height=\"110\" style=\"float:left; margin-right:20px;  margin-bottom:10px;\" class=\"alignnone size-full wp-image-765\" \/>Drei Jahre dauerte die Pause vom Eurovision Song Contest. \u00d6sterreich ist 2011 wieder dabei. Das ist eine wunderbare Nachricht. Auch der Fanclub freut sich, einen Beitrag aus \u00d6sterreich beim Song Contest zu h\u00f6ren und zu sehen. Wilde Spekulationen \u00fcber den oder die InterpretenIn gibt es jetzt schon im Vorfeld und K\u00fcnstler wie Christina St\u00fcrmer, Anna F., DJ \u00d6tzi, Hansi Hinterseer, W. Ambros, R. Fendrich, Katrin Lampe, Missy May werden genannt. Auch unsere Diana wird angef\u00fchrt, was viel aussagt!<br clear=all><br \/>\nNun, wer wird es sein? Krone.at hat ein Voting veranstaltet und das Ergebnis kannst Du <strong><a href=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/voting_krone.at_song_contest.jpg\">hier<\/a><\/strong> abrufen.<br \/>\nInteressant sind die Prozentzahlen von Diana im Verh\u00e4ltnis zu so renommierten K\u00fcnstlern wie Fendrich oder Ambros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie der ORF auf seiner Website mitteilt, wird \u00d6sterreich beim Eurovision Song Contest 2011 wieder vertreten sein. &nbsp; Drei Jahre dauerte die Pause vom Eurovision Song Contest. \u00d6sterreich ist 2011 wieder dabei. Das ist eine wunderbare Nachricht. Auch der Fanclub freut sich, einen Beitrag aus \u00d6sterreich beim Song Contest zu h\u00f6ren und zu sehen. Wilde [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-764","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/comments?post=764"}],"version-history":[{"count":0,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/764\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/media?parent=764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/categories?post=764"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/tags?post=764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}