{"id":880,"date":"2011-03-31T19:15:29","date_gmt":"2011-03-31T17:15:29","guid":{"rendered":"http:\/\/www.zweitfrau.eu\/wordpress\/?p=880"},"modified":"2011-03-31T19:15:29","modified_gmt":"2011-03-31T17:15:29","slug":"das-war-nockherberg-2011","status":"publish","type":"post","link":"http:\/\/www.zweitfrau.eu\/wordpress\/das-war-nockherberg-2011\/","title":{"rendered":"Das war Nockherberg 2011"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.muenchen.de\/\">m\u00fcnchen.de<\/a><\/strong>, das offizielle Stadtportal bringt ein Foto von Diana am Schlagzeug im Dirndl und schreibt am 23. M\u00e4rz 2011:<br \/>\n&nbsp;<\/p>\n<blockquote><p><strong>Nockherberg 2011<\/strong><br \/>\n<strong>Tradition und Premiere auf dem Nockherberg<\/strong><br \/>\n&nbsp;<br \/>\n<a href=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/diana_nockherberg_2011.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.zweitfrau.eu\/wordpress\/wp-content\/uploads\/diana_nockherberg_2011_tbn.jpg\" alt=\"diana_nockherberg_2011_tbn\" title=\"diana_nockherberg_2011_tbn\" width=\"150\" height=\"150\" style=\"float:left; margin-right:20px;  margin-bottom:10px;\" class=\"alignnone size-full wp-image-881\" \/><\/a>Auf den Anstich des ersten Salvator-Fasses im Paulaner am Nockherberg folgt traditionell das Politiker-Derbleck\u2019n in Form von einer deftigen Fastenpredigt und einem kabarettistischen Singspiel, bei denen den Politikern der Spiegel vorgehalten wird. Erstmals schl\u00fcpfte dieses Jahr eine Frau in die Rolle des Fastenpredigers: Als Mutter der bayerischen Nation verteilte Kabarettistin Luise Kinseher in Gestalt der Bavaria verbale Watschn an ihre unartigen Politiker-Kinder.<br \/>\n<br \/>\nIm Singspiel verliehen diesmal die Politiker einen Preis an ihre W\u00e4hler: So erhielten der Wutb\u00fcrger und die deutsche Aische den &#8222;Ude 2011&#8220;. Auf der B\u00fchne sangen und stritten die Doubles von Karl-Theodor zu Guttenberg, Angela Merkel, Christian Ude, Markus S\u00f6der und vielen weiteren Politikern.<br \/>\nFoto: Immanuel Rahman\n<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>m\u00fcnchen.de, das offizielle Stadtportal bringt ein Foto von Diana am Schlagzeug im Dirndl und schreibt am 23. M\u00e4rz 2011: &nbsp; Nockherberg 2011 Tradition und Premiere auf dem Nockherberg &nbsp; Auf den Anstich des ersten Salvator-Fasses im Paulaner am Nockherberg folgt traditionell das Politiker-Derbleck\u2019n in Form von einer deftigen Fastenpredigt und einem kabarettistischen Singspiel, bei denen [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-880","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/comments?post=880"}],"version-history":[{"count":0,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/posts\/880\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/media?parent=880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/categories?post=880"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/wordpress\/wp-json\/wp\/v2\/tags?post=880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}