{"id":19,"date":"2011-03-15T11:06:15","date_gmt":"2011-03-15T11:06:15","guid":{"rendered":"http:\/\/www.zweitfrau.eu\/yoga\/?page_id=19"},"modified":"2018-12-20T15:20:26","modified_gmt":"2018-12-20T14:20:26","slug":"info","status":"publish","type":"page","link":"http:\/\/www.zweitfrau.eu\/yoga\/info\/","title":{"rendered":"Info"},"content":{"rendered":"<p>Infos zum Yogaunterricht mit der Zweitfrau:<\/p>\n<p>Die Kurse und Weiterbildung, sowie die Preise, erf\u00e4hrst Du auf<br \/>\n<strong><a href=\"http:\/\/www.yogamitdiana.com\/\" target=\"_blank\" rel=\"noopener\">Yoga mit Diana<\/a><\/strong><br \/>\nE-Mail Anmeldungen bitte bei\u00a0<a href=\"mailto:diana@yogamitdiana.com\"><strong>diana@yogamitdiana.com<\/strong><\/a>\u00a0oder +43699 15960375<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Infos zum Yogaunterricht mit der Zweitfrau: Die Kurse und Weiterbildung, sowie die Preise, erf\u00e4hrst Du auf Yoga mit Diana E-Mail Anmeldungen bitte bei\u00a0diana@yogamitdiana.com\u00a0oder +43699 15960375<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"open","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/pages\/19"}],"collection":[{"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":3,"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":56,"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/pages\/19\/revisions\/56"}],"wp:attachment":[{"href":"http:\/\/www.zweitfrau.eu\/yoga\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}